{"id":6670,"date":"2024-03-17T14:59:43","date_gmt":"2024-03-17T13:59:43","guid":{"rendered":"https:\/\/colonos.it\/?p=6670"},"modified":"2024-11-28T12:16:23","modified_gmt":"2024-11-28T11:16:23","slug":"spacal-ultimis-visions-dal-cjars","status":"publish","type":"post","link":"https:\/\/colonos.it\/furlan\/spacal-ultimis-visions-dal-cjars\/","title":{"rendered":"Spacal, ultimis visions dal Cjars"},"content":{"rendered":"<p>Inaugurazion da la mostre di pituris e incisions<br \/>\nMusichis balcanichis cun <strong>Fabio Zoratti<\/strong><\/p>\n<p>La mostre e propon lis ultimis oparis da la produzion pitoriche di Spacal e il percors retrospet\u00eef da la s\u00f4 opare grafiche.<br \/>\n&#8220;Ho acquistato molto dal mondo carsico, del quale si afferma sia aspro ed avaro per natura.<br \/>\nForse pu\u00f2 essere vero per coloro che non lo comprendono, non riescono a penetrarne<br \/>\nl&#8217;essenza, a svelarne l&#8217;arcano. Ad essi il Carso certo non si schiude nella sua maestosit\u00e0 e direi bellezza spirituale&#8230; Qui \u00e8 nata ed ha prosperato la cultura contadina, che ancor oggi si riflette in molte case carsiche. L&#8217;amore per questa terra e tanto radicato in me, da permettermi di attingerne senza fine per creare\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inaugurazion<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts\/6670"}],"collection":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/comments?post=6670"}],"version-history":[{"count":2,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts\/6670\/revisions"}],"predecessor-version":[{"id":6674,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts\/6670\/revisions\/6674"}],"wp:attachment":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/media?parent=6670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/categories?post=6670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/tags?post=6670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}