{"id":3650,"date":"2021-07-19T14:18:20","date_gmt":"2021-07-19T12:18:20","guid":{"rendered":"https:\/\/colonos.it\/?p=3650"},"modified":"2024-11-28T12:17:32","modified_gmt":"2024-11-28T11:17:32","slug":"grazie-philippe","status":"publish","type":"post","link":"https:\/\/colonos.it\/furlan\/grazie-philippe\/","title":{"rendered":"Grazie Philippe"},"content":{"rendered":"<p><em>ricuart di Philippe Daverio,<\/em><br \/>\n<em>ami\u0300 dai Colonos e dal Friu\u0302l<\/em><\/p>\n<p>cun <strong>Elena Gregori Daverio<\/strong><br \/>\ndocuments video e testemoneancis<br \/>\ncoments musica\u0302ls <strong>Paolo Forte<\/strong> (armoniche)<\/p>\n<p>\u25cb prenotazions su <a href=\"https:\/\/www.eventbrite.it\/e\/biglietti-grazie-philippe-166306153181\"><strong>Eventbrite.com<\/strong><\/a><br \/>\n\u25cf s\u2019al plu\u0302f &gt; Auditorium comuna\u0302l di Lestize<\/p>\n<p>Une serade par ricuarda\u0302 intune maniere semplice ma sincere un ami\u0300, riva\u0302t par la prime volte ai Colonos ai 3 di Setembar dal 2004 par une event di presentazion di un dai siei artiscj preferi\u0302ts, Giuliano Mauri, che l\u2019associazion cultura\u0302l e veve invida\u0302t a realiza\u0302 sul puest il sugjesti\u0302f Templi Vegjeta\u0302l. Di che\u0302 volte Daverio si e\u0300 considera\u0302t un militant dai Colonos, di lui defini\u0302ts plui voltis \u201ccentra\u0302l di resistence cultura\u0302l\u201d, consacrant une tradizion che par 16 agns un dau\u0302r chel altri lu a\u0300 jodu\u0302t protagonist di incuintris memorabii cuntun public di grandis ocasions. \u201cO vevi cjata\u0302t cheste situazion dal dut no spietade, chest lu\u0302c cetant sperimenta\u0302l &#8211; parce\u0300 che ta la realta\u0302t al e\u0300 un agriturisim &#8211; dula\u0300 ch\u2019al jere un public infini\u0302t. Al jere ancjetant dificil imagjina\u0302si une robe dal gjenar, parvie che il Friu\u0302l lu cogno\u0300s, lu vevi frecuenta\u0302t di cuant ch\u2019o jeri frut. E l\u2019idee che li e fos une societa\u0302t cussi\u0300 articolade e curiose, interessade a dibati, a fevela\u0302 di argoments che par solit no si fevele, al jere avonde comovint\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incuintri cultur\u00e2l<\/p>\n","protected":false},"author":3,"featured_media":3703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts\/3650"}],"collection":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/comments?post=3650"}],"version-history":[{"count":7,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts\/3650\/revisions"}],"predecessor-version":[{"id":3992,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/posts\/3650\/revisions\/3992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/media\/3703"}],"wp:attachment":[{"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/media?parent=3650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/categories?post=3650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colonos.it\/furlan\/wp-json\/wp\/v2\/tags?post=3650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}